{"id":910,"date":"2026-02-02T19:45:00","date_gmt":"2026-02-02T19:45:00","guid":{"rendered":"https:\/\/astro.alphacen.org\/?page_id=910"},"modified":"2026-02-14T09:52:16","modified_gmt":"2026-02-14T09:52:16","slug":"cafe-guatemala","status":"publish","type":"page","link":"https:\/\/astro.alphacen.org\/en\/cafe-guatemala\/","title":{"rendered":"CAFE en Guatemala"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"910\" class=\"elementor elementor-910\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-923813e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"923813e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-65f6668\" data-id=\"65f6668\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ac5b85c elementor-widget elementor-widget-heading\" data-id=\"ac5b85c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-xxl\"><h style=\"color:#262754\">Taller astron\u00f3mico CAFE en guatemala<\/h2><br><br>CAFE invita a las mentes j\u00f3venes a explorar el universo con oradores \ninternacionales en Guatemala durante una semana de actividades pr\u00e1cticas y te\u00f3ricas sobre astronom\u00eda.\n<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a68d3b\" data-id=\"2a68d3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a022f9 elementor-widget elementor-widget-image\" data-id=\"6a022f9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"796\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-1024x796.png\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-1024x796.png 1024w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-300x233.png 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-768x597.png 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-1536x1195.png 1536w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-2048x1593.png 2048w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/logo-CAFE-2025-16x12.png 16w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a59c5cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a59c5cb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0bf21bd\" data-id=\"0bf21bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cfce10 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5cfce10\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/forms.gle\/mWvgvdFksVvxudNc7\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Registro<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3e66ef\" data-id=\"d3e66ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4bd08d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4bd08d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cc31da\" data-id=\"6cc31da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dd4d8ca elementor-widget elementor-widget-text-editor\" data-id=\"dd4d8ca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h1 style=\"text-align: center;\"><span style=\"color: #ffffff;\">Nuestra Misi\u00f3n<\/span><\/h1><h4 class=\"has-theme-1-color has-text-color has-link-color has-albert-sans-font-family wp-elements-f385fd4bb42a8d1443d1e523e47bfc6e wp-block-paragraph\"><span style=\"color: #ffffff;\">En Guatemala, las ciencias astron\u00f3micas son de las \u00e1reas cient\u00edficas que m\u00e1s atraen a la juventud. Sin embargo, actualmente no constituyen un tema central dentro del Curr\u00edculum Nacional Base. Esto limita el acceso que tienen las y los estudiantes a material confiable.<\/span><\/h4><h4 class=\"has-theme-1-color has-text-color has-link-color has-albert-sans-font-family wp-elements-e67341a16e7e48578e59e8cda1846ae0 wp-block-paragraph\"><span style=\"color: #ffffff;\">Este taller busca mostrar a las y los j\u00f3venes guatemaltecos que s\u00ed hay personas haciendo ciencia en Guatemala, que existen esfuerzos activos para fortalecer la ciencia y la tecnolog\u00eda en el pa\u00eds, e iniciarles en la investigaci\u00f3n cient\u00edfica desde su realidad acad\u00e9mica actual. De esta manera facilitarles el acceso a redes de contacto dentro de la academia y fortalecer su perfil acad\u00e9mico para aumentar su competitividad para becas y pasant\u00edas internacionales.<\/span><\/h4><h1 class=\"wp-block-heading has-text-align-center has-theme-1-color has-text-color has-link-color has-albert-sans-font-family wp-elements-752eb037befcf7cb79e02fb13210bea7\" style=\"text-align: center;\"><span style=\"color: #ffffff;\">Nuestra Visi\u00f3n<\/span><\/h1><h4 class=\"has-theme-1-color has-text-color has-link-color has-albert-sans-font-family wp-elements-39e0c2cb676b6a8d1ec048d100c40f9f wp-block-paragraph\"><span style=\"color: #ffffff;\">Convertir este taller en una actividad recurrente, que inspire y capacite a distintos grupos de estudiantes guatemaltecos, contribuyendo al desarrollo de una comunidad cient\u00edfica s\u00f3lida y conectada con el mundo.<\/span><\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9045d23 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9045d23\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38aa9ad\" data-id=\"38aa9ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68aa9ea elementor-widget elementor-widget-text-editor\" data-id=\"68aa9ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<h1 class=\"has-text-align-center has-link-color wp-elements-7ddeee0f7ac4e52ce36cbe8d1de7145a wp-block-post-title has-text-color has-albert-sans-font-family\">Horario de actividades<\/h1><h4 class=\"has-text-color has-link-color has-albert-sans-font-family wp-elements-d8f33362573122cc6e81a455255ac33a wp-block-paragraph\">El taller se llevar\u00e1 a cabo del 13 al 17 de julio del a\u00f1o 2026 en los siguientes horarios:<\/h4>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-63b8173 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63b8173\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7097b6a\" data-id=\"7097b6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ac01a3 elementor-widget elementor-widget-shortcode\" data-id=\"0ac01a3\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"footable_parent_912\"\n     class=\"footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui\">\n                <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"912\" data-filter-delay=\"500\" aria-label=\"Horario_Caf\u00e9 - Sheet1.csv\"            id=\"footable_912\"\n           data-unique_identifier=\"ninja_table_unique_id_536415222_912\"\n           class=\"foo-table ninja_footable foo_table_912 ninja_table_unique_id_536415222_912 ui table  nt_type_ajax_table selectable striped vertical_centered  footable-paging-right\">\n                <colgroup>\n                            <col class=\"ninja_column_0\">\n                            <col class=\"ninja_column_1\">\n                            <col class=\"ninja_column_2\">\n                            <col class=\"ninja_column_3\">\n                            <col class=\"ninja_column_4\">\n                            <col class=\"ninja_column_5\">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ac33ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ac33ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-affb319\" data-id=\"affb319\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5aab4bd elementor-widget elementor-widget-heading\" data-id=\"5aab4bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Faltan<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5837b8b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5837b8b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d909b6a\" data-id=\"d909b6a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e923ee3 elementor-widget elementor-widget-elementskit-countdown-timer\" data-id=\"e923ee3\" data-element_type=\"widget\" data-widget_type=\"elementskit-countdown-timer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"elementskit-countdown-container text-center\">\n                    <div class=\"elementskit-countdown-timer-4 ekit-countdown\"  data-date-ekit-day=\"Days\" data-date-ekit-hour=\"Hours\" data-date-ekit-minute=\"Minutes\" data-date-ekit-second=\"Seconds\" data-ekit-countdown=\"2026-05-01 06:59\" data-finish-title=\"Countdown is finished!\" data-finish-content=\"Lorem Ipsum is simply dummy text of the printing and typesetting industry. Lorem Ipsum has been the industry&#039;s standard dummy text ever since the 1500s\"><\/div>\n                <\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-189ca06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"189ca06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18c1859\" data-id=\"18c1859\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cfcb11 elementor-widget elementor-widget-heading\" data-id=\"8cfcb11\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">para finalizar las inscripciones<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-79c9b01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"79c9b01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84820a7\" data-id=\"84820a7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b27a6e elementor-widget elementor-widget-heading\" data-id=\"8b27a6e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-heading-title elementor-size-xxl\">Conoce al equipo<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59abb6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59abb6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c404f42\" data-id=\"c404f42\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eaccee elementor-widget elementor-widget-image\" data-id=\"7eaccee\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-1024x1024.jpeg 1024w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-300x300.jpeg 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-150x150.jpeg 150w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-768x769.jpeg 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1-12x12.jpeg 12w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Paula-1.jpeg 1077w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6104dbf\" data-id=\"6104dbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f3104 elementor-widget elementor-widget-text-editor\" data-id=\"36f3104\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h4 class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #000000;\"><strong>Paula G\u00e1lvez Molina\/Presidenta del Comit\u00e9 Organizador<\/strong><\/span><\/h4><p class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #000000;\">Es f\u00edsica guatemalteca y estudiante de doctorado en el Departamento de F\u00edsica y Astronom\u00eda en University of Delaware. Obtuvo una doble licenciatura en F\u00edsica y Matem\u00e1tica en Emporia State University en 2022, donde fue reconocida como estudiante destacada por su desempe\u00f1o acad\u00e9mico. Su investigaci\u00f3n se enfoca en la detecci\u00f3n de rayos c\u00f3smicos mediante ondas de radio, utilizando datos del IceCube Neutrino Observatory y del proyecto NASA POEMMA Balloon Radio, as\u00ed como herramientas de aprendizaje autom\u00e1tico. Ha participado en escuelas internacionales de investigaci\u00f3n en Chile, Alaska y Alemania, y ha trabajado como analista de datos en el Instituto Nacional de Estad\u00edstica de Guatemala.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-416f085 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"416f085\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-72cb0fc\" data-id=\"72cb0fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4939962 elementor-widget elementor-widget-text-editor\" data-id=\"4939962\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h4 class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\"><strong>Rodrigo Sacahu\u00ed Reyes\/Vicepresidente del Comit\u00e9 Organizador<\/strong><\/span><\/h4><p class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\">Es licenciado en F\u00edsica Aplicada por la Universidad de San Carlos de Guatemala, donde actualmente es profesor titular. Realiz\u00f3 sus estudios de maestr\u00eda y doctorado en Astrof\u00edsica en el Instituto de Astronom\u00eda de la UNAM, en M\u00e9xico, y estudios posdoctorales en el Instituto Nacional de Ciencias del Espacio de Brasil. Su investigaci\u00f3n se centra en la astrof\u00edsica de altas energ\u00edas. Ha recibido reconocimientos por su labor, incluyendo el premio \u201cH\u00e9roes de la Investigaci\u00f3n\u201d de la editorial Wiley y distinciones por excelencia acad\u00e9mica en la USAC. Es el \u00fanico miembro individual de la Uni\u00f3n Astron\u00f3mica Internacional en Guatemala y miembro fundador de Astrof\u00edsica Centroamericana y del Caribe.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a1f303\" data-id=\"2a1f303\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1155eae elementor-widget elementor-widget-image\" data-id=\"1155eae\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-1024x1024.jpeg 1024w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-300x300.jpeg 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-150x150.jpeg 150w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-768x768.jpeg 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1-12x12.jpeg 12w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Rodrigo-1.jpeg 1254w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-44f0468 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"44f0468\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dbeb81c\" data-id=\"dbeb81c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-624631b elementor-widget elementor-widget-image\" data-id=\"624631b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-1024x1024.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-1024x1024.jpeg 1024w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-300x300.jpeg 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-150x150.jpeg 150w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-768x769.jpeg 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1-12x12.jpeg 12w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Abel-1.jpeg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-64510df\" data-id=\"64510df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc4d09b elementor-widget elementor-widget-text-editor\" data-id=\"dc4d09b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h4 class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\"><strong>Abel Hern\u00e1ndez Garc\u00eda\/Coordinador del Comit\u00e9 Organizador Local<\/strong><\/span><\/h4><p class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\">Es coordinador del \u00e1rea acad\u00e9mica del Profesorado y Licenciatura con Especialidad en Matem\u00e1tica y F\u00edsica, as\u00ed como de la asignatura de Formaci\u00f3n Integral Bases de Investigaci\u00f3n I. Desde 2022 se desempe\u00f1a como catedr\u00e1tico horario en la Universidad Rafael Land\u00edvar y, desde 2023, forma parte de la coordinaci\u00f3n general de la Olimpiada Guatemalteca de Astronom\u00eda (OGA). Cuenta con un Profesorado en Ense\u00f1anza Media en Filosof\u00eda y una Licenciatura en Educaci\u00f3n y Aprendizaje por la Universidad Rafael Land\u00edvar, as\u00ed como un Profesorado en Ense\u00f1anza Media en Matem\u00e1tica y F\u00edsica por la Universidad del<\/span><br \/><span style=\"color: #333333;\">Valle de Guatemala.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-57061dd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57061dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67672bd\" data-id=\"67672bd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ff6d7a elementor-widget elementor-widget-text-editor\" data-id=\"3ff6d7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h4 class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\"><strong>Giovanna Rene\u00e9 Hern\u00e1ndez\/Miembro del Comit\u00e9 Organizador<\/strong><\/span><\/h4><p class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\">Es estudiante de \u00faltimo a\u00f1o de la Licenciatura en F\u00edsica Aplicada en la Universidad de San Carlos de Guatemala. Ha complementado su formaci\u00f3n con talleres y escuelas especializadas en astrof\u00edsica, entre ellas el Taller de Astrof\u00edsica de Altas Energ\u00edas y Cosmolog\u00eda (TAACO 2024) y la Escuela de Astronom\u00eda Alpha-Cen 2025. Ha participado activamente en proyectos de divulgaci\u00f3n cient\u00edfica, particularmente en astronom\u00eda. Fue colaboradora de la Olimpiada Guatemalteca de Astronom\u00eda y monitora en la MasterClass de IceCube en Guatemala. Sus intereses acad\u00e9micos se centran en la astrof\u00edsica moderna y en la ense\u00f1anza de las ciencias, con \u00e9nfasis en la divulgaci\u00f3n cient\u00edfica inclusiva.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8d4dc37\" data-id=\"8d4dc37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cde210f elementor-widget elementor-widget-image\" data-id=\"cde210f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"1024\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-1024x1024.jpg 1024w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-300x300.jpg 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-150x150.jpg 150w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-768x768.jpg 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1-12x12.jpg 12w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Giovanna-1.jpg 1065w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef0cb03 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef0cb03\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-73e256a\" data-id=\"73e256a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ab0545 elementor-widget elementor-widget-image\" data-id=\"1ab0545\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"960\" height=\"960\" src=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1.jpeg\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1.jpeg 960w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1-300x300.jpeg 300w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1-150x150.jpeg 150w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1-768x768.jpeg 768w, https:\/\/astro.alphacen.org\/wp-content\/uploads\/2026\/02\/Gabriel-1-12x12.jpeg 12w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41a4f7b\" data-id=\"41a4f7b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46296e3 elementor-widget elementor-widget-text-editor\" data-id=\"46296e3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><h4 class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\"><strong>Gabriel Mart\u00ednez Flores\/Miembro del Comit\u00e9 Organizador<\/strong><\/span><\/h4><p class=\"has-albert-sans-font-family wp-block-paragraph\"><span style=\"color: #333333;\">Es estudiante de IV Bachillerato en Ciencias y Letras en el Colegio Waldorf de Guatemala. Desde temprana edad ha mostrado un marcado inter\u00e9s por las ciencias y las matem\u00e1ticas, as\u00ed como por la comprensi\u00f3n de los fen\u00f3menos naturales. Actualmente se desempe\u00f1a como tesorero del consejo estudiantil y forma parte del comit\u00e9 organizador de CAFE. En su tiempo libre practica diversos deportes, destacando la bicicleta de monta\u00f1a como su actividad principal.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13e9b26 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13e9b26\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4875b87\" data-id=\"4875b87\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5066440 elementor-widget elementor-widget-heading\" data-id=\"5066440\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6560b87 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6560b87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d440a1e\" data-id=\"d440a1e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-062f916 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"062f916\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-fca6705\" href=\"https:\/\/instagram.com\/taller_cafe\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-tiktok elementor-repeater-item-11ab49d\" href=\"https:\/\/tiktok.com\/@taller_cafe\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Tiktok<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-tiktok\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-4293e8c\" href=\"https:\/\/www.facebook.com\/share\/1C5N8LWGoA\/?mibextid=wwXIfr\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<i class=\"fab fa-facebook\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ada1591 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ada1591\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c52f546\" data-id=\"c52f546\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dafeca elementor-widget elementor-widget-text-editor\" data-id=\"3dafeca\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<p>astrotaller.cafe@gmail.com<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Taller astron\u00f3mico CAFE en guatemala CAFE invita a las mentes j\u00f3venes a explorar el universo con oradores internacionales en Guatemala durante una semana de actividades pr\u00e1cticas y te\u00f3ricas sobre astronom\u00eda. Registro Nuestra Misi\u00f3n En Guatemala, las ciencias astron\u00f3micas son de las \u00e1reas cient\u00edficas que m\u00e1s atraen a la juventud. Sin embargo, actualmente no constituyen un &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/astro.alphacen.org\/en\/cafe-guatemala\/\"> <span class=\"screen-reader-text\">CAFE en Guatemala<\/span> Read More &raquo;<\/a><\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"_links":{"self":[{"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/pages\/910"}],"collection":[{"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/comments?post=910"}],"version-history":[{"count":70,"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/pages\/910\/revisions"}],"predecessor-version":[{"id":1008,"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/pages\/910\/revisions\/1008"}],"wp:attachment":[{"href":"https:\/\/astro.alphacen.org\/en\/wp-json\/wp\/v2\/media?parent=910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}